{"id":7952,"date":"2020-03-24T18:26:16","date_gmt":"2020-03-24T18:26:16","guid":{"rendered":"https:\/\/www.lottohoy.com\/?p=7952"},"modified":"2024-10-23T17:24:34","modified_gmt":"2024-10-23T16:24:34","slug":"kino","status":"publish","type":"post","link":"https:\/\/lottohoy.com\/es\/kino\/","title":{"rendered":"Kino Chileno, gana de muchas maneras"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El kino es sin duda unos de los juegos de azar m\u00e1s populares de Chile. Es el m\u00e1s antiguo (1991), despu\u00e9s del cl\u00e1sico \u201cboleto\u201d que data de 1921.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">En otro post de esta misma web, ya hablamos un poco en general de las <\/span><a href=\"https:\/\/lottohoy.com\/es\/loterias-de-chile\/\"><span style=\"font-weight: 400;\">diversas loter\u00edas de Chile<\/span><\/a><span style=\"font-weight: 400;\"> y las modalidades de juego para cada una de ellas. Aqu\u00ed nos centraremos m\u00e1s en el propio juego familiar de Kino y como se juega Kino.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>C\u00f3mo Jugar Kino<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">El juego consiste b\u00e1sicamente en seleccionar 14 n\u00fameros de una cartilla que contiene casillas numeradas del 1 al 25.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">En el sorteo se extraen de una t\u00f3mbola, una tras otra, las 14 bolillas numeradas que formar\u00e1n la combinaci\u00f3n ganadora, entre las 25\u00a0 que previamente al sorteo se hab\u00edan introducido.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">La cartilla de juego, tambi\u00e9n llamada volante, donde se debe realizar la selecci\u00f3n de los n\u00fameros para participar en el juego, se puede rellenar manualmente marcando las casilla deseadas, o dejando que el propio sistema aleatoriamente marque las casillas.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Cabe una tercera posibilidad y es marcar solamente algunas casillas numeradas y dejar que sea el propio sistema quien marque al azar los restantes n\u00fameros hasta completar una combinaci\u00f3n de 14 n\u00fameros.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Esta cartilla permite no solo participar para el juego principal de Kino, si no tambi\u00e9n a los juegos adicionales, hacer apuestas m\u00faltiples o combinadas y jugar para sorteos por adelantado.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfEn qu\u00e9 consisten las apuestas m\u00faltiples?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">La puesta m\u00faltiple o combinada, consiste en la posibilidad de a\u00f1adir a la combinaci\u00f3n simple de 14 n\u00fameros, hasta un m\u00e1ximo de 3 m\u00e1s, para tener m\u00e1s posibilidades de aciertos.<\/span><\/p>\r\n<ul>\r\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">A\u00f1adir un n\u00famero m\u00e1s (15) es el equivalente a jugar 15 juegos distintos.<\/span><\/li>\r\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">A\u00f1adir 2 n\u00fameros m\u00e1s a los catorce (16) equivale a 120 apuestas distintas<\/span><\/li>\r\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Y a\u00f1adir 3,\u00a0 hasta un m\u00e1ximo de 17 es jugar por 680 juegos o apuestas distintas<\/span><\/li>\r\n<\/ul>\r\n<p><span style=\"font-weight: 400;\">Kino tiene un pozo millonario al acertante de 14, que se ir\u00eda acumulando en caso de no haber acertante alguno de esa categor\u00eda en el sorteo.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de la categor\u00eda principal de 14 aciertos, tambi\u00e9n tiene premios para otras categor\u00edas con 13, 12, 11 y 10 aciertos.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfCu\u00e1nto cuesta el Kino?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">El precio de la apuesta b\u00e1sica para Kino es de $600 e incluye la participaci\u00f3n en las diversas categor\u00edas de premios (14, 13, 12, 11 y 10), adem\u00e1s de la categor\u00eda de premios al n\u00famero del cart\u00f3n.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfCu\u00e1ntos juegos adicionales tiene?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Al jugar el cart\u00f3n de kino, en todos los sorteos hay de manera conjunta y por el mismo precio de la apuesta un premio especial \u201cal n\u00famero del cart\u00f3n\u201d, con regalos que pueden ser casas, autos, viajes o dinero en met\u00e1lico entre otras muchas cosas m\u00e1s.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Adicionalmente el juego principal Kino, se puede complementar con otras variantes, por una m\u00f3dica cantidad a sumar al precio de la apuesta sencilla:<\/span><b><\/b><\/p>\r\n<ul>\r\n<li><b>Rekino<\/b><\/li>\r\n<\/ul>\r\n<ul>\r\n<li><b>Chanchito regal\u00f3n<\/b><\/li>\r\n<\/ul>\r\n<ul>\r\n<li><b>Combo marraqueta<\/b><\/li>\r\n<\/ul>\r\n<ul>\r\n<li><b>Chao jefe 50 a\u00f1os, heredable $1.000.000<\/b><\/li>\r\n<\/ul>\r\n<ul>\r\n<li><b>Chao jefe 50 a\u00f1os, heredable $2.000.000<\/b><\/li>\r\n<\/ul>\r\n<p>&nbsp;<\/p>\r\n<h3><b>Rekino<\/b><\/h3>\r\n<p><span style=\"font-weight: 400;\">En el juego del Rekino<\/span> <span style=\"font-weight: 400;\">participan los mismos cartones que en la jugada principal para una segunda extracci\u00f3n distinta de la primera para acertar los 14, y en caso de no haber acertante, el premio se acumula para sucesivos sorteos.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Jugar Rekino,\u00a0 tiene un costo a\u00f1adido de $400 y conlleva obligatoriamente participar conjuntamente en el juego base de kino. En total significa una jugada de $1000<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h3><b>Chanchito Regal\u00f3n<\/b><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/h3>\r\n<p><span style=\"font-weight: 400;\">Se trata de una tercera posibilidad de conseguir un premio millonario con 14 aciertos, siempre con la misma combinaci\u00f3n de la jugada principal, en una tercera extracci\u00f3n diferente a las anteriores.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Para participar en Chanchito Regal\u00f3n, se bebe jugar conjuntamente con el juego base de Kino + Rekino, y tiene un costo de $200, que en total ser\u00e1 de $1200<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h3><b>Combo Marraqueta, <\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/h3>\r\n<p><span style=\"font-weight: 400;\">Consiste en un premio de 1 Casa, 1 Auto y un Sueldo de $500.000 mensuales por 10 a\u00f1os para el ganador con 14 aciertos. La extracci\u00f3n del juego Combo Marraqueta es independiente de las extracciones de los otros juegos adicionales de Kino, y se participas con los mismos 14 n\u00fameros de la apuesta principal de Kino.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">El Combo marraqueta tiene un precio adicional de $100 que deber\u00e1 a\u00f1adirse obligatoriamente a jugar de manera conjunta al Kino + Rekino + Chanchito Regal\u00f3n. En total $1300<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h3><b>Chao jefe 50 a\u00f1os, heredable $1.000.000<\/b><\/h3>\r\n<p><span style=\"font-weight: 400;\">En una cuarta extracci\u00f3n diferente a las anteriores, el ganador que disponga loa 14 n\u00fameros de esta combinaci\u00f3n, percibir\u00e1 $1.000.000 mensuales durante un periodo de 50 a\u00f1os, siendo heredable ese premio<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">El precio de Chao jefe 50 a\u00f1os, heredable $1.000.000, es de $200 que deber\u00e1n a\u00f1adirse a las las jugadas de Kino + Rekino + Chanchito Regal\u00f3n + Combo marraqueta, un total de $1500.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h3><b>Chao jefe 50 a\u00f1os, heredable $2.000.000<\/b><\/h3>\r\n<p><span style=\"font-weight: 400;\">Como en el caso anterior y tambi\u00e9n de una quinta extracci\u00f3n diferente a las anteriores, el ganador obtiene $2.000.000 mensuales durante 50 a\u00f1os, e igualmente heredable en caso de fallecimiento.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Jugar Chao jefe 50 a\u00f1os, heredable $2.000.000, significa jugar conjuntamente el base de Kino + Rekino + Chanchito Regal\u00f3n + Combo marraqueta + Chao jefe 50 a\u00f1os, heredable $1.000.000, por un importe de a\u00f1adido de $500, lo que har\u00eda un total de $2000.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfCon cu\u00e1ntos aciertos se gana el Kino?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">La primera categor\u00eda corresponde a los 14 aciertos, el premio se reparte entre los posibles ganadores de esa categor\u00eda, y en caso de no haber acertante alguno, el importe previsto se acumula para sorteo siguiente.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Trece (13) aciertos, como en el caso de primera categor\u00eda, el premio asignado a esta categor\u00eda, se repartir\u00e1 entre todos los acertantes de la misma, y en caso de no haber acertante el importe se acumular\u00e1 para el siguiente sorteo.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Doce (12) aciertos, a los acertantes de esta categor\u00eda se les asigna un premio fijo m\u00ednimo de $5000 a cada uno.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Once (11) aciertos, tiene un premio asignado de $1.500 a cada uno de los acertantes.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Diez (10) aciertos, tiene un premio equivalente al reintegro de la cantidad de la apuesta base, es decir $600<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">El premio destinado al N\u00famero del cart\u00f3n, puede<\/span><span style=\"font-weight: 400;\"> ser variables dependiendo del sorteo, y puede ser en especie, en especie o su equivalente en dinero o en dinero. Este premio se informa de manera anticipada en la secci\u00f3n \u201cNovedades\u201d de la p\u00e1gina web oficial.\u00a0<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h3><b>\u00bfD\u00f3nde se puede comprar?<\/b><\/h3>\r\n<p><span style=\"font-weight: 400;\">Las apuestas de Kino, bien sean simples o combinadas, se pueden jugar por internet a trav\u00e9s de la web oficial de loteria.cl, en las agencias oficiales de loter\u00eda repartidas por todo el pa\u00eds, y tambi\u00e9n a trav\u00e9s de supermercados y comercios multiservicios habilitados, que dispongan de los correspondientes equipos emisores del ticket validado.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfCuando se sortea el Kino?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Los sorteos de Kino se realizan los mi\u00e9rcoles, viernes y domingos, a las 22:30 hora local de Santiago de Chile, (GTM &#8211; 04:00)<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>\u00bfD\u00f3nde se cobran los premios?<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Si se jug\u00f3 a trav\u00e9s de internet en la p\u00e1gina oficial de<\/span><a href=\"https:\/\/www.loteria.cl\/\"><span style=\"font-weight: 400;\"> loteria.cl,<\/span><\/a><span style=\"font-weight: 400;\"> los premios, a excepci\u00f3n de los de primera categor\u00eda (14 aciertos) se ingresan directamente en la cuenta de usuario registrado.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Si desea retirarlo, deber\u00e1 seguir las instrucciones que se le indica en la propia web, y en un plazo de 15 d\u00edas h\u00e1biles recibir\u00e1 el dinero en su cuenta bancaria.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Los premios de Kino para las categor\u00edas de 13, 12, 11 y 10 aciertos y premios al n\u00famero de cart\u00f3n en dinero, pueden realizarse en la red de agencias oficiales de Loter\u00eda.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Si el premio obtenido no puede ser pagado por la Agencia, esta misma enviar\u00e1 a las oficinas de Loter\u00eda un formulario de Validaci\u00f3n al que se adjuntar\u00e1 el cart\u00f3n ganador y fotocopia de la c\u00e9dula de identidad del ganador, entregando una copia del documento al ganador.<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<p><span style=\"font-weight: 400;\">Para las Categor\u00edas Kino 14 Aciertos y premios al n\u00famero de cart\u00f3n, asi como los premios de los juegos complementarios (ReKino, Chanchito Regal\u00f3n, Combo Marraqueta, Chao jefe 50 a\u00f1os heredable $1.000.000 y Chao jefe 50 a\u00f1os heredable $2.000.000 deber\u00e1 realizarse en las oficinas de Loter\u00eda en Concepci\u00f3n, o en las oficinas de Santiago,<\/span><\/p>\r\n<p><i><span style=\"font-weight: 400;\">Si alguno de estos premios fue obtenido por apuestas jugadas a trav\u00e9s de internet el ganador debe realizar el cobro del premio en las oficinas de Santiago o Concepci\u00f3n.<\/span><\/i><\/p>\r\n<p><span style=\"font-weight: 400;\">Cuando el juego se hubiese realizado a trav\u00e9s Agencia o comercio autorizado, y el importe de premio sea superior a 20 veces\u00a0 el precio de venta, se descontar\u00e1 un 2% a favor del agente comisionista vendedor<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>Caducidad de los premios de Kino<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Los premios no reclamados, caducan a los 60 d\u00edas a contar desde el d\u00eda del sorteo, y una vez concluido dicho plazo, se considerar\u00e1n caducados legalmente.\u00a0<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<h2><b>Impuestos sobre los premios de loter\u00edas de Chile<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Los premios en general tienen la consideraci\u00f3n de \u201crentas\u201d y se debe abonar un pago del 15% en calidad de impuesto \u00fanico de la Ley de Renta<\/span><\/p>\r\n<p>&nbsp;<\/p><p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El kino es sin duda unos de los juegos de azar m\u00e1s populares de Chile. Es el m\u00e1s antiguo (1991), despu\u00e9s del cl\u00e1sico \u201cboleto\u201d que data de 1921. En otro post de esta misma web, ya hablamos un poco en general de las diversas loter\u00edas de Chile y las modalidades de juego para cada una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-7952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kino,la loteria de Chile con multiples formas de ganar<\/title>\n<meta name=\"description\" content=\"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lottohoy.com\/es\/kino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kino,la loteria de Chile con multiples formas de ganar\" \/>\n<meta property=\"og:description\" content=\"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lottohoy.com\/es\/kino\/\" \/>\n<meta property=\"og:site_name\" content=\"Lottohoy\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-24T18:26:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T16:24:34+00:00\" \/>\n<meta name=\"author\" content=\"Marc Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marc Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/\",\"url\":\"https:\/\/lottohoy.com\/es\/kino\/\",\"name\":\"Kino,la loteria de Chile con multiples formas de ganar\",\"isPartOf\":{\"@id\":\"https:\/\/lottohoy.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-03-24T18:26:16+00:00\",\"dateModified\":\"2024-10-23T16:24:34+00:00\",\"author\":{\"@id\":\"https:\/\/lottohoy.com\/es\/#\/schema\/person\/80d8c421f8dfe806853f0c1a4aeeaed7\"},\"description\":\"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda\",\"breadcrumb\":{\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lottohoy.com\/es\/kino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lottohoy.com\/es\/kino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lottohoy.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kino Chileno, gana de muchas maneras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lottohoy.com\/es\/#website\",\"url\":\"https:\/\/lottohoy.com\/es\/\",\"name\":\"Lottohoy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lottohoy.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/lottohoy.com\/es\/#\/schema\/person\/80d8c421f8dfe806853f0c1a4aeeaed7\",\"name\":\"Marc Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lottohoy.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3c660792fa5d25f37d3ff8c3f7d5815e1eb3279bf818f28764df0268e023002?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3c660792fa5d25f37d3ff8c3f7d5815e1eb3279bf818f28764df0268e023002?s=96&d=mm&r=g\",\"caption\":\"Marc Martin\"},\"url\":\"https:\/\/lottohoy.com\/es\/author\/jose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kino,la loteria de Chile con multiples formas de ganar","description":"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lottohoy.com\/es\/kino\/","og_locale":"es_ES","og_type":"article","og_title":"Kino,la loteria de Chile con multiples formas de ganar","og_description":"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda","og_url":"https:\/\/lottohoy.com\/es\/kino\/","og_site_name":"Lottohoy","article_published_time":"2020-03-24T18:26:16+00:00","article_modified_time":"2024-10-23T16:24:34+00:00","author":"Marc Martin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marc Martin","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lottohoy.com\/es\/kino\/","url":"https:\/\/lottohoy.com\/es\/kino\/","name":"Kino,la loteria de Chile con multiples formas de ganar","isPartOf":{"@id":"https:\/\/lottohoy.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lottohoy.com\/es\/kino\/#primaryimage"},"image":{"@id":"https:\/\/lottohoy.com\/es\/kino\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-03-24T18:26:16+00:00","dateModified":"2024-10-23T16:24:34+00:00","author":{"@id":"https:\/\/lottohoy.com\/es\/#\/schema\/person\/80d8c421f8dfe806853f0c1a4aeeaed7"},"description":"La loteria chilena de Kino, ofrece la posibilidad de jugar con la misma combinaci\u00f3n y partipar para varios sorteos en el mismo d\u00eda","breadcrumb":{"@id":"https:\/\/lottohoy.com\/es\/kino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lottohoy.com\/es\/kino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lottohoy.com\/es\/kino\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/lottohoy.com\/es\/kino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lottohoy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Kino Chileno, gana de muchas maneras"}]},{"@type":"WebSite","@id":"https:\/\/lottohoy.com\/es\/#website","url":"https:\/\/lottohoy.com\/es\/","name":"Lottohoy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lottohoy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lottohoy.com\/es\/#\/schema\/person\/80d8c421f8dfe806853f0c1a4aeeaed7","name":"Marc Martin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lottohoy.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a3c660792fa5d25f37d3ff8c3f7d5815e1eb3279bf818f28764df0268e023002?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3c660792fa5d25f37d3ff8c3f7d5815e1eb3279bf818f28764df0268e023002?s=96&d=mm&r=g","caption":"Marc Martin"},"url":"https:\/\/lottohoy.com\/es\/author\/jose\/"}]}},"_links":{"self":[{"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/posts\/7952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/comments?post=7952"}],"version-history":[{"count":1,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/posts\/7952\/revisions"}],"predecessor-version":[{"id":11369,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/posts\/7952\/revisions\/11369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lottohoy.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/media?parent=7952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/categories?post=7952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lottohoy.com\/es\/wp-json\/wp\/v2\/tags?post=7952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}